{"id":163526,"date":"2023-11-01T15:34:01","date_gmt":"2023-11-01T19:34:01","guid":{"rendered":"https:\/\/www.cfea.com\/?p=163526"},"modified":"2023-11-01T15:34:33","modified_gmt":"2023-11-01T19:34:33","slug":"nouvelle-mesure-en-jordanie-sur-lalimentaion-de-la-volaile","status":"publish","type":"post","link":"https:\/\/www.cfea.com\/fr\/nouvelle-mesure-en-jordanie-sur-lalimentaion-de-la-volaile\/","title":{"rendered":"Nouvelle mesure en Jordanie sur l&#8217;alimentaion de la volaile"},"content":{"rendered":"<p><strong>L\u2019actualit\u00e9s du AAC\u2019s Secr\u00e9tariat \u00e0 l\u2019acc\u00e8s aux march\u00e9s<\/strong><\/p>\n<p>Ce message a pour but de vous informer que la Jordanie a notifi\u00e9 une nouvelle mesure \u00e0 l&#8217;Organisation mondiale du commerce le 20 octobre 2023 concernant la viande de volaille. Conform\u00e9ment \u00e0 la notification, les importations de viande de volaille et d&#8217;abats comestibles devront provenir de volailles \u00e9lev\u00e9es avec des aliments exempts de poudres animales provenant de ruminants. L&#8217;ambassade du Canada en Jordanie a \u00e9t\u00e9 en contact avec des repr\u00e9sentants du gouvernement jordanien qui ont indiqu\u00e9 que le texte de la mesure n&#8217;\u00e9tait pas encore disponible mais que les nouvelles exigences devraient entrer en vigueur au d\u00e9but de l&#8217;ann\u00e9e prochaine.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019actualit\u00e9s du AAC\u2019s Secr\u00e9tariat \u00e0 l\u2019acc\u00e8s aux march\u00e9s Ce message a pour but de vous informer que la Jordanie a notifi\u00e9 une nouvelle mesure \u00e0 l&#8217;Organisation mondiale du commerce le 20 octobre 2023 concernant la viande de volaille. Conform\u00e9ment \u00e0 la notification, les importations de viande de volaille et d&#8217;abats comestibles devront provenir de volailles [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[89],"tags":[],"class_list":["post-163526","post","type-post","status-publish","format-standard","hentry","category-public-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nouvelle mesure en Jordanie sur l&#039;alimentaion de la volaile - l\u2019Association canadienne des exportateurs \u00e0 l\u2019alimentation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cfea.com\/fr\/nouvelle-mesure-en-jordanie-sur-lalimentaion-de-la-volaile\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouvelle mesure en Jordanie sur l&#039;alimentaion de la volaile - l\u2019Association canadienne des exportateurs \u00e0 l\u2019alimentation\" \/>\n<meta property=\"og:description\" content=\"L\u2019actualit\u00e9s du AAC\u2019s Secr\u00e9tariat \u00e0 l\u2019acc\u00e8s aux march\u00e9s Ce message a pour but de vous informer que la Jordanie a notifi\u00e9 une nouvelle mesure \u00e0 l&#8217;Organisation mondiale du commerce le 20 octobre 2023 concernant la viande de volaille. Conform\u00e9ment \u00e0 la notification, les importations de viande de volaille et d&#8217;abats comestibles devront provenir de volailles [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cfea.com\/fr\/nouvelle-mesure-en-jordanie-sur-lalimentaion-de-la-volaile\/\" \/>\n<meta property=\"og:site_name\" content=\"l\u2019Association canadienne des exportateurs \u00e0 l\u2019alimentation\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/canadianfoodexportersassociation\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-01T19:34:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-01T19:34:33+00:00\" \/>\n<meta name=\"author\" content=\"Susan Powell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cfea\" \/>\n<meta name=\"twitter:site\" content=\"@cfea\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Susan Powell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cfea.com\\\/fr\\\/nouvelle-mesure-en-jordanie-sur-lalimentaion-de-la-volaile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cfea.com\\\/fr\\\/nouvelle-mesure-en-jordanie-sur-lalimentaion-de-la-volaile\\\/\"},\"author\":{\"name\":\"Susan Powell\",\"@id\":\"https:\\\/\\\/www.cfea.com\\\/#\\\/schema\\\/person\\\/b690f9c0dcd7a78217270b2493d8b748\"},\"headline\":\"Nouvelle mesure en Jordanie sur l&#8217;alimentaion de la volaile\",\"datePublished\":\"2023-11-01T19:34:01+00:00\",\"dateModified\":\"2023-11-01T19:34:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cfea.com\\\/fr\\\/nouvelle-mesure-en-jordanie-sur-lalimentaion-de-la-volaile\\\/\"},\"wordCount\":130,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cfea.com\\\/#organization\"},\"articleSection\":[\"Publique\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cfea.com\\\/fr\\\/nouvelle-mesure-en-jordanie-sur-lalimentaion-de-la-volaile\\\/\",\"url\":\"https:\\\/\\\/www.cfea.com\\\/fr\\\/nouvelle-mesure-en-jordanie-sur-lalimentaion-de-la-volaile\\\/\",\"name\":\"Nouvelle mesure en Jordanie sur l'alimentaion de la volaile - l\u2019Association canadienne des exportateurs \u00e0 l\u2019alimentation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cfea.com\\\/#website\"},\"datePublished\":\"2023-11-01T19:34:01+00:00\",\"dateModified\":\"2023-11-01T19:34:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cfea.com\\\/fr\\\/nouvelle-mesure-en-jordanie-sur-lalimentaion-de-la-volaile\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cfea.com\\\/fr\\\/nouvelle-mesure-en-jordanie-sur-lalimentaion-de-la-volaile\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cfea.com\\\/fr\\\/nouvelle-mesure-en-jordanie-sur-lalimentaion-de-la-volaile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.cfea.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelle mesure en Jordanie sur l&#8217;alimentaion de la volaile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cfea.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cfea.com\\\/\",\"name\":\"Canadian Food Exporters Association (CFEA)\",\"description\":\"Your Gateway to the World!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cfea.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cfea.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cfea.com\\\/#organization\",\"name\":\"Canadian Food Exporters Association\",\"url\":\"https:\\\/\\\/www.cfea.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cfea.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cfea.com\\\/wp-content\\\/uploads\\\/cfea-logo-login.png\",\"contentUrl\":\"https:\\\/\\\/www.cfea.com\\\/wp-content\\\/uploads\\\/cfea-logo-login.png\",\"width\":320,\"height\":120,\"caption\":\"Canadian Food Exporters Association\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cfea.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/canadianfoodexportersassociation\",\"https:\\\/\\\/x.com\\\/cfea\",\"https:\\\/\\\/www.instagram.com\\\/cfeacdn\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/cfeacdn\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cfea.com\\\/#\\\/schema\\\/person\\\/b690f9c0dcd7a78217270b2493d8b748\",\"name\":\"Susan Powell\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc5763e98ac9a62279ed00ce2616ed3416da920a5c99cf4a769969e35b49a1c7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc5763e98ac9a62279ed00ce2616ed3416da920a5c99cf4a769969e35b49a1c7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc5763e98ac9a62279ed00ce2616ed3416da920a5c99cf4a769969e35b49a1c7?s=96&d=mm&r=g\",\"caption\":\"Susan Powell\"},\"url\":\"https:\\\/\\\/www.cfea.com\\\/fr\\\/author\\\/susan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nouvelle mesure en Jordanie sur l'alimentaion de la volaile - l\u2019Association canadienne des exportateurs \u00e0 l\u2019alimentation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cfea.com\/fr\/nouvelle-mesure-en-jordanie-sur-lalimentaion-de-la-volaile\/","og_locale":"fr_FR","og_type":"article","og_title":"Nouvelle mesure en Jordanie sur l'alimentaion de la volaile - l\u2019Association canadienne des exportateurs \u00e0 l\u2019alimentation","og_description":"L\u2019actualit\u00e9s du AAC\u2019s Secr\u00e9tariat \u00e0 l\u2019acc\u00e8s aux march\u00e9s Ce message a pour but de vous informer que la Jordanie a notifi\u00e9 une nouvelle mesure \u00e0 l&#8217;Organisation mondiale du commerce le 20 octobre 2023 concernant la viande de volaille. Conform\u00e9ment \u00e0 la notification, les importations de viande de volaille et d&#8217;abats comestibles devront provenir de volailles [&hellip;]","og_url":"https:\/\/www.cfea.com\/fr\/nouvelle-mesure-en-jordanie-sur-lalimentaion-de-la-volaile\/","og_site_name":"l\u2019Association canadienne des exportateurs \u00e0 l\u2019alimentation","article_publisher":"https:\/\/www.facebook.com\/canadianfoodexportersassociation","article_published_time":"2023-11-01T19:34:01+00:00","article_modified_time":"2023-11-01T19:34:33+00:00","author":"Susan Powell","twitter_card":"summary_large_image","twitter_creator":"@cfea","twitter_site":"@cfea","twitter_misc":{"\u00c9crit par":"Susan Powell","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cfea.com\/fr\/nouvelle-mesure-en-jordanie-sur-lalimentaion-de-la-volaile\/#article","isPartOf":{"@id":"https:\/\/www.cfea.com\/fr\/nouvelle-mesure-en-jordanie-sur-lalimentaion-de-la-volaile\/"},"author":{"name":"Susan Powell","@id":"https:\/\/www.cfea.com\/#\/schema\/person\/b690f9c0dcd7a78217270b2493d8b748"},"headline":"Nouvelle mesure en Jordanie sur l&#8217;alimentaion de la volaile","datePublished":"2023-11-01T19:34:01+00:00","dateModified":"2023-11-01T19:34:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cfea.com\/fr\/nouvelle-mesure-en-jordanie-sur-lalimentaion-de-la-volaile\/"},"wordCount":130,"publisher":{"@id":"https:\/\/www.cfea.com\/#organization"},"articleSection":["Publique"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.cfea.com\/fr\/nouvelle-mesure-en-jordanie-sur-lalimentaion-de-la-volaile\/","url":"https:\/\/www.cfea.com\/fr\/nouvelle-mesure-en-jordanie-sur-lalimentaion-de-la-volaile\/","name":"Nouvelle mesure en Jordanie sur l'alimentaion de la volaile - l\u2019Association canadienne des exportateurs \u00e0 l\u2019alimentation","isPartOf":{"@id":"https:\/\/www.cfea.com\/#website"},"datePublished":"2023-11-01T19:34:01+00:00","dateModified":"2023-11-01T19:34:33+00:00","breadcrumb":{"@id":"https:\/\/www.cfea.com\/fr\/nouvelle-mesure-en-jordanie-sur-lalimentaion-de-la-volaile\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cfea.com\/fr\/nouvelle-mesure-en-jordanie-sur-lalimentaion-de-la-volaile\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cfea.com\/fr\/nouvelle-mesure-en-jordanie-sur-lalimentaion-de-la-volaile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.cfea.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouvelle mesure en Jordanie sur l&#8217;alimentaion de la volaile"}]},{"@type":"WebSite","@id":"https:\/\/www.cfea.com\/#website","url":"https:\/\/www.cfea.com\/","name":"Canadian Food Exporters Association (CFEA)","description":"Your Gateway to the World!","publisher":{"@id":"https:\/\/www.cfea.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cfea.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.cfea.com\/#organization","name":"Canadian Food Exporters Association","url":"https:\/\/www.cfea.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cfea.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.cfea.com\/wp-content\/uploads\/cfea-logo-login.png","contentUrl":"https:\/\/www.cfea.com\/wp-content\/uploads\/cfea-logo-login.png","width":320,"height":120,"caption":"Canadian Food Exporters Association"},"image":{"@id":"https:\/\/www.cfea.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/canadianfoodexportersassociation","https:\/\/x.com\/cfea","https:\/\/www.instagram.com\/cfeacdn\/","https:\/\/www.linkedin.com\/company\/cfeacdn\/"]},{"@type":"Person","@id":"https:\/\/www.cfea.com\/#\/schema\/person\/b690f9c0dcd7a78217270b2493d8b748","name":"Susan Powell","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/fc5763e98ac9a62279ed00ce2616ed3416da920a5c99cf4a769969e35b49a1c7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fc5763e98ac9a62279ed00ce2616ed3416da920a5c99cf4a769969e35b49a1c7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fc5763e98ac9a62279ed00ce2616ed3416da920a5c99cf4a769969e35b49a1c7?s=96&d=mm&r=g","caption":"Susan Powell"},"url":"https:\/\/www.cfea.com\/fr\/author\/susan\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cfea.com\/fr\/wp-json\/wp\/v2\/posts\/163526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfea.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfea.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfea.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfea.com\/fr\/wp-json\/wp\/v2\/comments?post=163526"}],"version-history":[{"count":1,"href":"https:\/\/www.cfea.com\/fr\/wp-json\/wp\/v2\/posts\/163526\/revisions"}],"predecessor-version":[{"id":163527,"href":"https:\/\/www.cfea.com\/fr\/wp-json\/wp\/v2\/posts\/163526\/revisions\/163527"}],"wp:attachment":[{"href":"https:\/\/www.cfea.com\/fr\/wp-json\/wp\/v2\/media?parent=163526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfea.com\/fr\/wp-json\/wp\/v2\/categories?post=163526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfea.com\/fr\/wp-json\/wp\/v2\/tags?post=163526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}