{"id":165224,"date":"2024-06-27T15:03:27","date_gmt":"2024-06-27T19:03:27","guid":{"rendered":"https:\/\/www.cfea.com\/?p=165224"},"modified":"2024-06-27T15:03:58","modified_gmt":"2024-06-27T19:03:58","slug":"adoption-elargie-de-mon-acia-pour-les-exportations-de-vegetaux-vers-les-etats-unis","status":"publish","type":"post","link":"https:\/\/www.cfea.com\/fr\/adoption-elargie-de-mon-acia-pour-les-exportations-de-vegetaux-vers-les-etats-unis\/","title":{"rendered":"Adoption \u00e9largie de Mon ACIA pour les exportations de v\u00e9g\u00e9taux vers les \u00c9tats-Unis"},"content":{"rendered":"<p><strong>L\u2019actualit\u00e9s du Agence canadienne d&#8217;Inspection des aliments<\/strong><\/p>\n<p>En janvier\u00a02024, l\u2019Agence canadienne d\u2019inspection des aliments (ACIA) a lanc\u00e9 une approche d\u2019adoption progressive des demandes phytosanitaires num\u00e9riques par l\u2019interm\u00e9diaire de Mon ACIA pour les exportations de v\u00e9g\u00e9taux vers les \u00c9tats-Unis (\u00c9.-U.). Depuis lors, certains participants utilisent Mon ACIA pour pr\u00e9senter des demandes de services d\u2019exportation en ligne \u00e0 l\u2019ACIA plut\u00f4t que d\u2019envoyer par courriel le formulaire Demande d\u2019inspection des exportations et de certification phytosanitaire (CFIA\/ACIA\u00a03369) d\u00fbment rempli. Les certificats demand\u00e9s par l\u2019interm\u00e9diaire de Mon ACIA sont d\u00e9livr\u00e9s sous forme de certificats phytosanitaires \u00e9lectroniques (ePhyto). Les ePhytos sont envoy\u00e9s directement au d\u00e9partement de l\u2019Agriculture des \u00c9.-U., Animal and Plant Health Inspection Service (USDA-APHIS) \u00e0 l\u2019aide d\u2019un \u00e9change de donn\u00e9es de gouvernement \u00e0 gouvernement (G2G). Une copie certifi\u00e9e du ePhyto peut \u00eatre consult\u00e9e et imprim\u00e9e \u00e0 partir de Mon ACIA; les certificats phytosanitaires originaux sur papier ne sont plus d\u00e9livr\u00e9s.<\/p>\n<p>\u00c0 partir du 17\u00a0juin\u00a02024, l\u2019ACIA augmente progressivement le nombre d\u2019exportateurs invit\u00e9s \u00e0 utiliser Mon ACIA pour la certification des v\u00e9g\u00e9taux et des produits v\u00e9g\u00e9taux \u00e0 destination des \u00c9.-U.<\/p>\n<p>Mon ACIA peut \u00eatre utilis\u00e9 pour pr\u00e9senter des demandes de certificats phytosanitaires d\u2019exportation vers les \u00c9.-U. Les demandes d\u2019exportation vers d\u2019autres pays de destination doivent continuer \u00e0 \u00eatre pr\u00e9sent\u00e9es aux bureaux locaux de l\u2019ACIA au moyen du formulaire Demande d\u2019inspection des exportations et de certification phytosanitaire (CFIA\/ACIA\u00a03369).<\/p>\n<p><strong>Remarque \u2013 l\u2019utilisation de Mon ACIA ne signifie pas que les exigences actuelles en mati\u00e8re d\u2019exportation phytosanitaire ont \u00e9t\u00e9 modifi\u00e9es.<\/strong><\/p>\n<ul>\n<li><span style=\"font-style: normal; font-variant-caps: normal;\">Par exemple, les envois de semences vers les \u00c9.-U. qui utilisent actuellement les certificats d\u2019analyse\u00a0PPQ925 et CFIA5289 ou d\u2019autres certificats continueront \u00e0 les utiliser.<\/span><\/li>\n<li>Aucune nouvelle exigence en mati\u00e8re d\u2019exportation n\u2019est ajout\u00e9e. Ainsi, les exportations vers les \u00c9.-U. qui ne n\u00e9cessitent actuellement pas de certificat phytosanitaire continueront \u00e0 ne pas n\u00e9cessiter de certificat phytosanitaire.<\/li>\n<li>Les produits horticoles qui sont actuellement exp\u00e9di\u00e9s dans le cadre du Programme de certification des serres et du Programme canadien de certification des p\u00e9pini\u00e8res continueront \u00e0 l\u2019\u00eatre. Ce processus demeurera tel quel.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019actualit\u00e9s du Agence canadienne d&#8217;Inspection des aliments En janvier\u00a02024, l\u2019Agence canadienne d\u2019inspection des aliments (ACIA) a lanc\u00e9 une approche d\u2019adoption progressive des demandes phytosanitaires num\u00e9riques par l\u2019interm\u00e9diaire de Mon ACIA pour les exportations de v\u00e9g\u00e9taux vers les \u00c9tats-Unis (\u00c9.-U.). Depuis lors, certains participants utilisent Mon ACIA pour pr\u00e9senter des demandes de services d\u2019exportation en ligne [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[89],"tags":[],"class_list":["post-165224","post","type-post","status-publish","format-standard","hentry","category-public-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Adoption \u00e9largie de Mon ACIA pour les exportations de v\u00e9g\u00e9taux vers les \u00c9tats-Unis - l\u2019Association canadienne des exportateurs \u00e0 l\u2019alimentation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cfea.com\/fr\/adoption-elargie-de-mon-acia-pour-les-exportations-de-vegetaux-vers-les-etats-unis\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adoption \u00e9largie de Mon ACIA pour les exportations de v\u00e9g\u00e9taux vers les \u00c9tats-Unis - l\u2019Association canadienne des exportateurs \u00e0 l\u2019alimentation\" \/>\n<meta property=\"og:description\" content=\"L\u2019actualit\u00e9s du Agence canadienne d&#8217;Inspection des aliments En janvier\u00a02024, l\u2019Agence canadienne d\u2019inspection des aliments (ACIA) a lanc\u00e9 une approche d\u2019adoption progressive des demandes phytosanitaires num\u00e9riques par l\u2019interm\u00e9diaire de Mon ACIA pour les exportations de v\u00e9g\u00e9taux vers les \u00c9tats-Unis (\u00c9.-U.). Depuis lors, certains participants utilisent Mon ACIA pour pr\u00e9senter des demandes de services d\u2019exportation en ligne [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cfea.com\/fr\/adoption-elargie-de-mon-acia-pour-les-exportations-de-vegetaux-vers-les-etats-unis\/\" \/>\n<meta property=\"og:site_name\" content=\"l\u2019Association canadienne des exportateurs \u00e0 l\u2019alimentation\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/canadianfoodexportersassociation\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-27T19:03:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-27T19:03:58+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cfea\" \/>\n<meta name=\"twitter:site\" content=\"@cfea\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cfea.com\\\/fr\\\/adoption-elargie-de-mon-acia-pour-les-exportations-de-vegetaux-vers-les-etats-unis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cfea.com\\\/fr\\\/adoption-elargie-de-mon-acia-pour-les-exportations-de-vegetaux-vers-les-etats-unis\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.cfea.com\\\/#\\\/schema\\\/person\\\/0924cb2cabbe428f85b3d8cb4b6764af\"},\"headline\":\"Adoption \u00e9largie de Mon ACIA pour les exportations de v\u00e9g\u00e9taux vers les \u00c9tats-Unis\",\"datePublished\":\"2024-06-27T19:03:27+00:00\",\"dateModified\":\"2024-06-27T19:03:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cfea.com\\\/fr\\\/adoption-elargie-de-mon-acia-pour-les-exportations-de-vegetaux-vers-les-etats-unis\\\/\"},\"wordCount\":400,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cfea.com\\\/#organization\"},\"articleSection\":[\"Publique\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cfea.com\\\/fr\\\/adoption-elargie-de-mon-acia-pour-les-exportations-de-vegetaux-vers-les-etats-unis\\\/\",\"url\":\"https:\\\/\\\/www.cfea.com\\\/fr\\\/adoption-elargie-de-mon-acia-pour-les-exportations-de-vegetaux-vers-les-etats-unis\\\/\",\"name\":\"Adoption \u00e9largie de Mon ACIA pour les exportations de v\u00e9g\u00e9taux vers les \u00c9tats-Unis - l\u2019Association canadienne des exportateurs \u00e0 l\u2019alimentation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cfea.com\\\/#website\"},\"datePublished\":\"2024-06-27T19:03:27+00:00\",\"dateModified\":\"2024-06-27T19:03:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cfea.com\\\/fr\\\/adoption-elargie-de-mon-acia-pour-les-exportations-de-vegetaux-vers-les-etats-unis\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cfea.com\\\/fr\\\/adoption-elargie-de-mon-acia-pour-les-exportations-de-vegetaux-vers-les-etats-unis\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cfea.com\\\/fr\\\/adoption-elargie-de-mon-acia-pour-les-exportations-de-vegetaux-vers-les-etats-unis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.cfea.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adoption \u00e9largie de Mon ACIA pour les exportations de v\u00e9g\u00e9taux vers les \u00c9tats-Unis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cfea.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cfea.com\\\/\",\"name\":\"Canadian Food Exporters Association (CFEA)\",\"description\":\"Your Gateway to the World!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cfea.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cfea.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cfea.com\\\/#organization\",\"name\":\"Canadian Food Exporters Association\",\"url\":\"https:\\\/\\\/www.cfea.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cfea.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cfea.com\\\/wp-content\\\/uploads\\\/cfea-logo-login.png\",\"contentUrl\":\"https:\\\/\\\/www.cfea.com\\\/wp-content\\\/uploads\\\/cfea-logo-login.png\",\"width\":320,\"height\":120,\"caption\":\"Canadian Food Exporters Association\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cfea.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/canadianfoodexportersassociation\",\"https:\\\/\\\/x.com\\\/cfea\",\"https:\\\/\\\/www.instagram.com\\\/cfeacdn\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/cfeacdn\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cfea.com\\\/#\\\/schema\\\/person\\\/0924cb2cabbe428f85b3d8cb4b6764af\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a733a0ae4eaa9fd37c753090fd0244712934aec81912beb53e7ed72a43ba32c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a733a0ae4eaa9fd37c753090fd0244712934aec81912beb53e7ed72a43ba32c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a733a0ae4eaa9fd37c753090fd0244712934aec81912beb53e7ed72a43ba32c?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/www.cfea.com\\\/fr\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adoption \u00e9largie de Mon ACIA pour les exportations de v\u00e9g\u00e9taux vers les \u00c9tats-Unis - l\u2019Association canadienne des exportateurs \u00e0 l\u2019alimentation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cfea.com\/fr\/adoption-elargie-de-mon-acia-pour-les-exportations-de-vegetaux-vers-les-etats-unis\/","og_locale":"fr_FR","og_type":"article","og_title":"Adoption \u00e9largie de Mon ACIA pour les exportations de v\u00e9g\u00e9taux vers les \u00c9tats-Unis - l\u2019Association canadienne des exportateurs \u00e0 l\u2019alimentation","og_description":"L\u2019actualit\u00e9s du Agence canadienne d&#8217;Inspection des aliments En janvier\u00a02024, l\u2019Agence canadienne d\u2019inspection des aliments (ACIA) a lanc\u00e9 une approche d\u2019adoption progressive des demandes phytosanitaires num\u00e9riques par l\u2019interm\u00e9diaire de Mon ACIA pour les exportations de v\u00e9g\u00e9taux vers les \u00c9tats-Unis (\u00c9.-U.). Depuis lors, certains participants utilisent Mon ACIA pour pr\u00e9senter des demandes de services d\u2019exportation en ligne [&hellip;]","og_url":"https:\/\/www.cfea.com\/fr\/adoption-elargie-de-mon-acia-pour-les-exportations-de-vegetaux-vers-les-etats-unis\/","og_site_name":"l\u2019Association canadienne des exportateurs \u00e0 l\u2019alimentation","article_publisher":"https:\/\/www.facebook.com\/canadianfoodexportersassociation","article_published_time":"2024-06-27T19:03:27+00:00","article_modified_time":"2024-06-27T19:03:58+00:00","author":"admin","twitter_card":"summary_large_image","twitter_creator":"@cfea","twitter_site":"@cfea","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cfea.com\/fr\/adoption-elargie-de-mon-acia-pour-les-exportations-de-vegetaux-vers-les-etats-unis\/#article","isPartOf":{"@id":"https:\/\/www.cfea.com\/fr\/adoption-elargie-de-mon-acia-pour-les-exportations-de-vegetaux-vers-les-etats-unis\/"},"author":{"name":"admin","@id":"https:\/\/www.cfea.com\/#\/schema\/person\/0924cb2cabbe428f85b3d8cb4b6764af"},"headline":"Adoption \u00e9largie de Mon ACIA pour les exportations de v\u00e9g\u00e9taux vers les \u00c9tats-Unis","datePublished":"2024-06-27T19:03:27+00:00","dateModified":"2024-06-27T19:03:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cfea.com\/fr\/adoption-elargie-de-mon-acia-pour-les-exportations-de-vegetaux-vers-les-etats-unis\/"},"wordCount":400,"publisher":{"@id":"https:\/\/www.cfea.com\/#organization"},"articleSection":["Publique"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.cfea.com\/fr\/adoption-elargie-de-mon-acia-pour-les-exportations-de-vegetaux-vers-les-etats-unis\/","url":"https:\/\/www.cfea.com\/fr\/adoption-elargie-de-mon-acia-pour-les-exportations-de-vegetaux-vers-les-etats-unis\/","name":"Adoption \u00e9largie de Mon ACIA pour les exportations de v\u00e9g\u00e9taux vers les \u00c9tats-Unis - l\u2019Association canadienne des exportateurs \u00e0 l\u2019alimentation","isPartOf":{"@id":"https:\/\/www.cfea.com\/#website"},"datePublished":"2024-06-27T19:03:27+00:00","dateModified":"2024-06-27T19:03:58+00:00","breadcrumb":{"@id":"https:\/\/www.cfea.com\/fr\/adoption-elargie-de-mon-acia-pour-les-exportations-de-vegetaux-vers-les-etats-unis\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cfea.com\/fr\/adoption-elargie-de-mon-acia-pour-les-exportations-de-vegetaux-vers-les-etats-unis\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cfea.com\/fr\/adoption-elargie-de-mon-acia-pour-les-exportations-de-vegetaux-vers-les-etats-unis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.cfea.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Adoption \u00e9largie de Mon ACIA pour les exportations de v\u00e9g\u00e9taux vers les \u00c9tats-Unis"}]},{"@type":"WebSite","@id":"https:\/\/www.cfea.com\/#website","url":"https:\/\/www.cfea.com\/","name":"Canadian Food Exporters Association (CFEA)","description":"Your Gateway to the World!","publisher":{"@id":"https:\/\/www.cfea.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cfea.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.cfea.com\/#organization","name":"Canadian Food Exporters Association","url":"https:\/\/www.cfea.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cfea.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.cfea.com\/wp-content\/uploads\/cfea-logo-login.png","contentUrl":"https:\/\/www.cfea.com\/wp-content\/uploads\/cfea-logo-login.png","width":320,"height":120,"caption":"Canadian Food Exporters Association"},"image":{"@id":"https:\/\/www.cfea.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/canadianfoodexportersassociation","https:\/\/x.com\/cfea","https:\/\/www.instagram.com\/cfeacdn\/","https:\/\/www.linkedin.com\/company\/cfeacdn\/"]},{"@type":"Person","@id":"https:\/\/www.cfea.com\/#\/schema\/person\/0924cb2cabbe428f85b3d8cb4b6764af","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2a733a0ae4eaa9fd37c753090fd0244712934aec81912beb53e7ed72a43ba32c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2a733a0ae4eaa9fd37c753090fd0244712934aec81912beb53e7ed72a43ba32c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2a733a0ae4eaa9fd37c753090fd0244712934aec81912beb53e7ed72a43ba32c?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.cfea.com\/fr\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cfea.com\/fr\/wp-json\/wp\/v2\/posts\/165224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfea.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfea.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfea.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfea.com\/fr\/wp-json\/wp\/v2\/comments?post=165224"}],"version-history":[{"count":1,"href":"https:\/\/www.cfea.com\/fr\/wp-json\/wp\/v2\/posts\/165224\/revisions"}],"predecessor-version":[{"id":165225,"href":"https:\/\/www.cfea.com\/fr\/wp-json\/wp\/v2\/posts\/165224\/revisions\/165225"}],"wp:attachment":[{"href":"https:\/\/www.cfea.com\/fr\/wp-json\/wp\/v2\/media?parent=165224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfea.com\/fr\/wp-json\/wp\/v2\/categories?post=165224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfea.com\/fr\/wp-json\/wp\/v2\/tags?post=165224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}